{"id":19088,"date":"2026-05-06T04:23:36","date_gmt":"2026-05-06T02:23:36","guid":{"rendered":"https:\/\/lepatriotebenin.com\/?p=19088"},"modified":"2026-05-06T04:23:36","modified_gmt":"2026-05-06T02:23:36","slug":"independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise","status":"publish","type":"post","link":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/","title":{"rendered":"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise"},"content":{"rendered":"<p><em><strong>\u00c0 l\u2019occasion de la Journ\u00e9e mondiale de la libert\u00e9 de la presse, le pr\u00e9sident de l\u2019Union des professionnels des m\u00e9dias du B\u00e9nin (UPMB), Herv\u00e9 Prudence Hessou, a plaid\u00e9 pour un sursaut collectif en faveur d\u2019un environnement m\u00e9diatique plus libre, \u00e9thique et professionnel, \u00e0 travers quatre appels majeurs adress\u00e9s aux acteurs du secteur<\/strong><\/em>.<\/p>\n<p>R\u00e9unis le 3 mai dernier, les acteurs des m\u00e9dias b\u00e9ninois ont marqu\u00e9 la Journ\u00e9e mondiale de la libert\u00e9 de la presse dans un contexte pr\u00e9occupant. Devant des repr\u00e9sentants du Conseil national du patronat de l\u2019audiovisuel (CNPA-B\u00e9nin), de l\u2019Observatoire de la d\u00e9ontologie et de l\u2019\u00e9thique dans les m\u00e9dias (ODEM), ainsi que des responsables de la SRTB et de l\u2019ONIP, Herv\u00e9 Prudence Hessou a dress\u00e9 un constat sans d\u00e9tour : pr\u00e9carit\u00e9 persistante, cadre normatif contraignant et garanties insuffisantes pour la presse.<\/p>\n<p>En effet, au c\u0153ur de son intervention, il a lanc\u00e9 quatre appels structurants. D\u2019abord aux autorit\u00e9s publiques, il les invite \u00e0 consolider les acquis d\u00e9mocratiques et \u00e0 renforcer les garanties de la libert\u00e9 de la presse. Le responsable syndical a insist\u00e9 sur la n\u00e9cessit\u00e9 d\u2019un cadre r\u00e9glementaire \u00ab qui prot\u00e8ge sans contraindre abusivement \u00bb, dans un contexte o\u00f9 plusieurs professionnels ont \u00e9t\u00e9 inqui\u00e9t\u00e9s sur la base du code du num\u00e9rique. Ensuite, aux entreprises de presse, il a demand\u00e9 une am\u00e9lioration des conditions de travail et une professionnalisation accrue du secteur. \u00ab Les journalistes ne b\u00e9n\u00e9ficient ni de contrats stables, ni de salaires d\u00e9cents, encore moins d\u2019une couverture sociale ad\u00e9quate \u00bb, a-t-il d\u00e9plor\u00e9.<\/p>\n<p>Le troisi\u00e8me appel s\u2019adresse aux journalistes eux-m\u00eames o\u00f9 il les exhorte \u00e0 un sursaut d\u2019\u00e9thique, de rigueur et de responsabilit\u00e9 face aux d\u00e9fis de la d\u00e9sinformation et aux mutations technologiques, notamment l\u2019intelligence artificielle. Enfin, Herv\u00e9 Hessou a interpell\u00e9 le public, l\u2019invitant \u00e0 un usage responsable de l\u2019information et au d\u00e9veloppement de l\u2019esprit critique.<\/p>\n<p>Malgr\u00e9 les difficult\u00e9s, le pr\u00e9sident de l\u2019UPMB a salu\u00e9 le r\u00f4le des m\u00e9dias lors des derni\u00e8res \u00e9ch\u00e9ances \u00e9lectorales, rappelant leur place essentielle comme \u00ab quatri\u00e8me pouvoir \u00bb. Mais dans un contexte de recul du B\u00e9nin dans le classement de Reporters sans fronti\u00e8res, il appelle \u00e0 une mobilisation collective pour pr\u00e9server les fondements d\u00e9mocratiques et restaurer un climat propice \u00e0 l\u2019exercice du journalisme.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Gildas AHOGNI<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 l\u2019occasion de la Journ\u00e9e mondiale de la libert\u00e9 de la presse, le pr\u00e9sident de l\u2019Union des professionnels des m\u00e9dias du B\u00e9nin (UPMB), Herv\u00e9 Prudence Hessou, a plaid\u00e9 pour un&hellip;<\/p>\n","protected":false},"author":5,"featured_media":19089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-19088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise - Le Patriote<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise - Le Patriote\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l\u2019occasion de la Journ\u00e9e mondiale de la libert\u00e9 de la presse, le pr\u00e9sident de l\u2019Union des professionnels des m\u00e9dias du B\u00e9nin (UPMB), Herv\u00e9 Prudence Hessou, a plaid\u00e9 pour un&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Patriote\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-06T02:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lepatriotebenin.com\/wp-content\/uploads\/2026\/05\/presse-a.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaction\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaction\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/\"},\"author\":{\"name\":\"Redaction\",\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/#\\\/schema\\\/person\\\/2e7709b9c9cc313e452d1136af61690f\"},\"headline\":\"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise\",\"datePublished\":\"2026-05-06T02:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/\"},\"wordCount\":423,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lepatriotebenin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/presse-a.jpeg\",\"articleSection\":[\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/\",\"url\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/\",\"name\":\"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise - Le Patriote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lepatriotebenin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/presse-a.jpeg\",\"datePublished\":\"2026-05-06T02:23:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/#\\\/schema\\\/person\\\/2e7709b9c9cc313e452d1136af61690f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lepatriotebenin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/presse-a.jpeg\",\"contentUrl\":\"https:\\\/\\\/lepatriotebenin.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/presse-a.jpeg\",\"width\":780,\"height\":560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/index.php\\\/2026\\\/05\\\/06\\\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lepatriotebenin.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/#website\",\"url\":\"https:\\\/\\\/lepatriotebenin.com\\\/\",\"name\":\"Le Patriote\",\"description\":\"Le Patriote B\u00e9nin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lepatriotebenin.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lepatriotebenin.com\\\/#\\\/schema\\\/person\\\/2e7709b9c9cc313e452d1136af61690f\",\"name\":\"Redaction\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4c509357859ea2ca2cbb6d8812898a73e4ef1ef9934c2e591d7e32face734d1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4c509357859ea2ca2cbb6d8812898a73e4ef1ef9934c2e591d7e32face734d1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4c509357859ea2ca2cbb6d8812898a73e4ef1ef9934c2e591d7e32face734d1?s=96&d=mm&r=g\",\"caption\":\"Redaction\"},\"url\":\"https:\\\/\\\/lepatriotebenin.com\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise - Le Patriote","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/","og_locale":"fr_FR","og_type":"article","og_title":"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise - Le Patriote","og_description":"\u00c0 l\u2019occasion de la Journ\u00e9e mondiale de la libert\u00e9 de la presse, le pr\u00e9sident de l\u2019Union des professionnels des m\u00e9dias du B\u00e9nin (UPMB), Herv\u00e9 Prudence Hessou, a plaid\u00e9 pour un&hellip;","og_url":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/","og_site_name":"Le Patriote","article_published_time":"2026-05-06T02:23:36+00:00","og_image":[{"width":780,"height":560,"url":"https:\/\/lepatriotebenin.com\/wp-content\/uploads\/2026\/05\/presse-a.jpeg","type":"image\/jpeg"}],"author":"Redaction","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Redaction","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/#article","isPartOf":{"@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/"},"author":{"name":"Redaction","@id":"https:\/\/lepatriotebenin.com\/#\/schema\/person\/2e7709b9c9cc313e452d1136af61690f"},"headline":"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise","datePublished":"2026-05-06T02:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/"},"wordCount":423,"commentCount":0,"image":{"@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/#primaryimage"},"thumbnailUrl":"https:\/\/lepatriotebenin.com\/wp-content\/uploads\/2026\/05\/presse-a.jpeg","articleSection":["Soci\u00e9t\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/","url":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/","name":"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise - Le Patriote","isPartOf":{"@id":"https:\/\/lepatriotebenin.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/#primaryimage"},"image":{"@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/#primaryimage"},"thumbnailUrl":"https:\/\/lepatriotebenin.com\/wp-content\/uploads\/2026\/05\/presse-a.jpeg","datePublished":"2026-05-06T02:23:36+00:00","author":{"@id":"https:\/\/lepatriotebenin.com\/#\/schema\/person\/2e7709b9c9cc313e452d1136af61690f"},"breadcrumb":{"@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/#primaryimage","url":"https:\/\/lepatriotebenin.com\/wp-content\/uploads\/2026\/05\/presse-a.jpeg","contentUrl":"https:\/\/lepatriotebenin.com\/wp-content\/uploads\/2026\/05\/presse-a.jpeg","width":780,"height":560},{"@type":"BreadcrumbList","@id":"https:\/\/lepatriotebenin.com\/index.php\/2026\/05\/06\/independance-du-journaliste-quatre-appels-pour-sauver-la-presse-beninoise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lepatriotebenin.com\/"},{"@type":"ListItem","position":2,"name":"Ind\u00e9pendance du journaliste : Quatre appels pour sauver la presse b\u00e9ninoise"}]},{"@type":"WebSite","@id":"https:\/\/lepatriotebenin.com\/#website","url":"https:\/\/lepatriotebenin.com\/","name":"Le Patriote","description":"Le Patriote B\u00e9nin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lepatriotebenin.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/lepatriotebenin.com\/#\/schema\/person\/2e7709b9c9cc313e452d1136af61690f","name":"Redaction","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c4c509357859ea2ca2cbb6d8812898a73e4ef1ef9934c2e591d7e32face734d1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c4c509357859ea2ca2cbb6d8812898a73e4ef1ef9934c2e591d7e32face734d1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c4c509357859ea2ca2cbb6d8812898a73e4ef1ef9934c2e591d7e32face734d1?s=96&d=mm&r=g","caption":"Redaction"},"url":"https:\/\/lepatriotebenin.com"}]}},"_links":{"self":[{"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/posts\/19088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/comments?post=19088"}],"version-history":[{"count":1,"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/posts\/19088\/revisions"}],"predecessor-version":[{"id":19090,"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/posts\/19088\/revisions\/19090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/media\/19089"}],"wp:attachment":[{"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/media?parent=19088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/categories?post=19088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lepatriotebenin.com\/index.php\/wp-json\/wp\/v2\/tags?post=19088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}